{"id":7878,"date":"2018-12-10T16:35:24","date_gmt":"2018-12-10T15:35:24","guid":{"rendered":"http:\/\/dev-en.deron.de\/?p=7878"},"modified":"2019-01-17T17:21:43","modified_gmt":"2019-01-17T16:21:43","slug":"it-projekt-manager","status":"publish","type":"post","link":"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/","title":{"rendered":"IT Project Manager \/ Team Leader (m\/f\/d) Conception and Development of complex IT Processes"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h2><strong><em>Ihre Aufgabe<\/em><\/strong><\/h2>\n<ul>\n<li>Nach einer ma\u00dfgeschneiderten Einarbeitung \u00fcbernehmen Sie, in direkter Zusammenarbeit mit der Gesch\u00e4ftsf\u00fchrung, spannende Projekte zur Automatisierung von IT-Prozessen.<\/li>\n<li>Mit Ihren Consultants reisen Sie zu TOP-Kunden, analysieren deren IT-Infrastruktur sowie IT-Gesch\u00e4ftsprozesse, erheben Anforderungen und \u00fcbersetzen diese in detaillierte Prozessmodelle und individuelle Roadmaps.<\/li>\n<li>Sie leiten Expertengremien mit Fachbereich, IT und Compliance; erarbeiten gemeinsam Fachkonzepte, pr\u00e4sentieren die Ergebnisse den F\u00fchrungskr\u00e4ften und bereiten wesentliche Entscheidungen vor.<\/li>\n<li>In Ihrem Stuttgarter Office coachen Sie Ihr Team bei der Produktbewertung, Konzepterstellung (Requirement Engineering, IT-Architektur) u. Entwicklung kundenspezifischer Erg\u00e4nzungen \/ Schnittstellen (Java \/ XML).<\/li>\n<li>Sie haben den Projektfortschritt (time, quality, budget) stets fest im Griff, halten Ihre Projekte auf Erfolgskurs und liefern beim Kunden gewinnbringende, intelligente und hochwertige Systeme ab.<\/li>\n<li>Intern bringen Sie Ihre Ideen ein und machen deron jeden Tag ein kleines bisschen besser.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong><em>Ihr Profil <\/em><\/strong><\/h2>\n<p>Sie verf\u00fcgen \u00fcber\u2026<\/p>\n<ul>\n<li>Begeisterung f\u00fcr intelligente, schlagkr\u00e4ftige IT-Projekte mit echtem Mehrwert.<\/li>\n<li>Consultingerfahrung in leitender Position und sicheres Auftreten auf allen Managementebenen.<\/li>\n<li>Reisebereitschaft (durchschnittlich 1x Tag\/Woche).<\/li>\n<li>Gutes Deutsch und technisches Englisch.<\/li>\n<li>Erfahrung im Umgang mit Prozessen, eventgesteuerten Workflows und in der Benutzer- und Berechtigungsverwaltung.<\/li>\n<li>Kenntnisse in Java oder JavaScript (nur lesen!).<\/li>\n<li>einen Abschlu\u00df in Wirtschaftsinformatik oder vergleichbares Wissen.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Von Vorteil ist die Kenntnis\u2026<\/p>\n<ul>\n<li>eines Identity Management Produkts.<\/li>\n<li>hierarchischer u. relationaler Datenbanken.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong><em>Ihr Gewinn <\/em><\/strong><\/h2>\n<ul>\n<li>Expertenwissen, namhafte Kunden und \u00fcberzeugende L\u00f6sungen auf hohem Niveau machen dauerhaft Spa\u00df an der Arbeit.<\/li>\n<li>Direkt dem CEO unterstellt haben Sie beste M\u00f6glichkeiten sich einzubringen und Dinge zu bewegen.<\/li>\n<li>Flexible Arbeitsbedingungen (Gleitzeit, Homeoffice) und gro\u00dfz\u00fcgige R\u00e4umlichkeiten machen die Arbeit noch angenehmer.<\/li>\n<li>Sie genie\u00dfen zahlreiche Benefits wie gratis Obst und (Fair Trade) Getr\u00e4nke, Firmenhandy, Bahncard, diverse Zusch\u00fcsse,&#8230;<\/li>\n<li>Das \u00e4u\u00dferst kollegiale Betriebsklima l\u00e4sst sich in keiner Anzeige abbilden, das m\u00fcssen Sie selbst sehen!<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong><em>Ihre Bewerbung <\/em><\/strong><\/h2>\n<p>Bitte senden Sie Ihre Unterlagen unter Angabe Ihrer Gehaltsvorstellung und des fr\u00fchest m\u00f6glichen Eintrittstermins an: <a href=\"mailto:monika.scherrbacher@deron.de\">monika.scherrbacher@deron.de<\/a><\/p>\n<p>Schelmenwasenstra\u00dfe 32, 70567 Stuttgart<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ihre Aufgabe Nach einer ma\u00dfgeschneiderten Einarbeitung \u00fcbernehmen Sie, in direkter Zusammenarbeit mit der Gesch\u00e4ftsf\u00fchrung, spannende Projekte zur Automatisierung von IT-Prozessen. Mit Ihren Consultants reisen Sie zu TOP-Kunden, analysieren deren &hellip; <a href=\"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-7878","post","type-post","status-publish","format-standard","hentry","category-jobs-en","jobs-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IT Project Manager \/ Team Leader (m\/f\/d) Conception and Development of complex IT Processes - deron<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ralf Starke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/jobs-en\\\/2018\\\/it-projekt-manager\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/jobs-en\\\/2018\\\/it-projekt-manager\\\/\"},\"author\":{\"name\":\"Ralf Starke\",\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/#\\\/schema\\\/person\\\/7334ddf5fe711a317b4489ee7d72cc5c\"},\"headline\":\"IT Project Manager \\\/ Team Leader (m\\\/f\\\/d) Conception and Development of complex IT Processes\",\"datePublished\":\"2018-12-10T15:35:24+00:00\",\"dateModified\":\"2019-01-17T16:21:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/jobs-en\\\/2018\\\/it-projekt-manager\\\/\"},\"wordCount\":342,\"articleSection\":[\"Jobs\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/jobs-en\\\/2018\\\/it-projekt-manager\\\/\",\"url\":\"https:\\\/\\\/www.deron.de\\\/en\\\/jobs-en\\\/2018\\\/it-projekt-manager\\\/\",\"name\":\"IT Project Manager \\\/ Team Leader (m\\\/f\\\/d) Conception and Development of complex IT Processes - deron\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/#website\"},\"datePublished\":\"2018-12-10T15:35:24+00:00\",\"dateModified\":\"2019-01-17T16:21:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/#\\\/schema\\\/person\\\/7334ddf5fe711a317b4489ee7d72cc5c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/jobs-en\\\/2018\\\/it-projekt-manager\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deron.de\\\/en\\\/jobs-en\\\/2018\\\/it-projekt-manager\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/jobs-en\\\/2018\\\/it-projekt-manager\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deron.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IT Project Manager \\\/ Team Leader (m\\\/f\\\/d) Conception and Development of complex IT Processes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.deron.de\\\/en\\\/\",\"name\":\"deron\",\"description\":\"Identity &amp; Access Management\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deron.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deron.de\\\/en\\\/#\\\/schema\\\/person\\\/7334ddf5fe711a317b4489ee7d72cc5c\",\"name\":\"Ralf Starke\",\"url\":\"https:\\\/\\\/www.deron.de\\\/en\\\/author\\\/starke\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IT Project Manager \/ Team Leader (m\/f\/d) Conception and Development of complex IT Processes - deron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/","twitter_misc":{"Written by":"Ralf Starke","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/#article","isPartOf":{"@id":"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/"},"author":{"name":"Ralf Starke","@id":"https:\/\/www.deron.de\/en\/#\/schema\/person\/7334ddf5fe711a317b4489ee7d72cc5c"},"headline":"IT Project Manager \/ Team Leader (m\/f\/d) Conception and Development of complex IT Processes","datePublished":"2018-12-10T15:35:24+00:00","dateModified":"2019-01-17T16:21:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/"},"wordCount":342,"articleSection":["Jobs"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/","url":"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/","name":"IT Project Manager \/ Team Leader (m\/f\/d) Conception and Development of complex IT Processes - deron","isPartOf":{"@id":"https:\/\/www.deron.de\/en\/#website"},"datePublished":"2018-12-10T15:35:24+00:00","dateModified":"2019-01-17T16:21:43+00:00","author":{"@id":"https:\/\/www.deron.de\/en\/#\/schema\/person\/7334ddf5fe711a317b4489ee7d72cc5c"},"breadcrumb":{"@id":"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.deron.de\/en\/jobs-en\/2018\/it-projekt-manager\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deron.de\/en\/"},{"@type":"ListItem","position":2,"name":"IT Project Manager \/ Team Leader (m\/f\/d) Conception and Development of complex IT Processes"}]},{"@type":"WebSite","@id":"https:\/\/www.deron.de\/en\/#website","url":"https:\/\/www.deron.de\/en\/","name":"deron","description":"Identity &amp; Access Management","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deron.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.deron.de\/en\/#\/schema\/person\/7334ddf5fe711a317b4489ee7d72cc5c","name":"Ralf Starke","url":"https:\/\/www.deron.de\/en\/author\/starke\/"}]}},"_links":{"self":[{"href":"https:\/\/www.deron.de\/en\/wp-json\/wp\/v2\/posts\/7878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deron.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deron.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deron.de\/en\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deron.de\/en\/wp-json\/wp\/v2\/comments?post=7878"}],"version-history":[{"count":4,"href":"https:\/\/www.deron.de\/en\/wp-json\/wp\/v2\/posts\/7878\/revisions"}],"predecessor-version":[{"id":8075,"href":"https:\/\/www.deron.de\/en\/wp-json\/wp\/v2\/posts\/7878\/revisions\/8075"}],"wp:attachment":[{"href":"https:\/\/www.deron.de\/en\/wp-json\/wp\/v2\/media?parent=7878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deron.de\/en\/wp-json\/wp\/v2\/categories?post=7878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deron.de\/en\/wp-json\/wp\/v2\/tags?post=7878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}